{"id":985,"count":1,"description":"","link":"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/","name":"Alkoholmonopol","slug":"alkoholmonopol","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alkoholmonopol Archive - bierversuche.ch<\/title>\n<meta name=\"description\" content=\"bierversuche.ch Alkoholmonopol\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alkoholmonopol Archive - bierversuche.ch\" \/>\n<meta property=\"og:description\" content=\"bierversuche.ch Alkoholmonopol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/\" \/>\n<meta property=\"og:site_name\" content=\"bierversuche.ch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bierversuche\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/\",\"url\":\"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/\",\"name\":\"Alkoholmonopol Archive - bierversuche.ch\",\"isPartOf\":{\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/#website\"},\"description\":\"bierversuche.ch Alkoholmonopol\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.bierversuche.ch\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alkoholmonopol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/#website\",\"url\":\"https:\/\/www.bierversuche.ch\/blog\/\",\"name\":\"bierversuche.ch\",\"description\":\"Craft Beer Blog\",\"publisher\":{\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bierversuche.ch\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/#organization\",\"name\":\"bierversuche\",\"url\":\"https:\/\/www.bierversuche.ch\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.bierversuche.ch\/blog\/wp-content\/uploads\/2013\/10\/Bierversuche_final_ohne_background-e1380636421999.png?fit=120%2C120&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.bierversuche.ch\/blog\/wp-content\/uploads\/2013\/10\/Bierversuche_final_ohne_background-e1380636421999.png?fit=120%2C120&ssl=1\",\"width\":120,\"height\":120,\"caption\":\"bierversuche\"},\"image\":{\"@id\":\"https:\/\/www.bierversuche.ch\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bierversuchech\",\"https:\/\/x.com\/bierversuche\",\"https:\/\/www.instagram.com\/bierversuche\/\",\"https:\/\/www.youtube.com\/channel\/UCeL4NwY3vPvisauq_X7N8ZA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alkoholmonopol Archive - bierversuche.ch","description":"bierversuche.ch Alkoholmonopol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/","og_locale":"de_DE","og_type":"article","og_title":"Alkoholmonopol Archive - bierversuche.ch","og_description":"bierversuche.ch Alkoholmonopol","og_url":"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/","og_site_name":"bierversuche.ch","twitter_card":"summary_large_image","twitter_site":"@bierversuche","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/","url":"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/","name":"Alkoholmonopol Archive - bierversuche.ch","isPartOf":{"@id":"https:\/\/www.bierversuche.ch\/blog\/#website"},"description":"bierversuche.ch Alkoholmonopol","breadcrumb":{"@id":"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bierversuche.ch\/blog\/tag\/alkoholmonopol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.bierversuche.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Alkoholmonopol"}]},{"@type":"WebSite","@id":"https:\/\/www.bierversuche.ch\/blog\/#website","url":"https:\/\/www.bierversuche.ch\/blog\/","name":"bierversuche.ch","description":"Craft Beer Blog","publisher":{"@id":"https:\/\/www.bierversuche.ch\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bierversuche.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.bierversuche.ch\/blog\/#organization","name":"bierversuche","url":"https:\/\/www.bierversuche.ch\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bierversuche.ch\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.bierversuche.ch\/blog\/wp-content\/uploads\/2013\/10\/Bierversuche_final_ohne_background-e1380636421999.png?fit=120%2C120&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.bierversuche.ch\/blog\/wp-content\/uploads\/2013\/10\/Bierversuche_final_ohne_background-e1380636421999.png?fit=120%2C120&ssl=1","width":120,"height":120,"caption":"bierversuche"},"image":{"@id":"https:\/\/www.bierversuche.ch\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bierversuchech","https:\/\/x.com\/bierversuche","https:\/\/www.instagram.com\/bierversuche\/","https:\/\/www.youtube.com\/channel\/UCeL4NwY3vPvisauq_X7N8ZA"]}]}},"_links":{"self":[{"href":"https:\/\/www.bierversuche.ch\/blog\/wp-json\/wp\/v2\/tags\/985"}],"collection":[{"href":"https:\/\/www.bierversuche.ch\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bierversuche.ch\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bierversuche.ch\/blog\/wp-json\/wp\/v2\/posts?tags=985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}